{"id":5245,"date":"2022-07-23T08:07:17","date_gmt":"2022-07-23T16:07:17","guid":{"rendered":"https:\/\/www.gudusoft.com\/?p=5245"},"modified":"2022-09-17T14:18:03","modified_gmt":"2022-09-17T22:18:03","slug":"how-to-succeed-in-data-governance","status":"publish","type":"post","link":"https:\/\/www.gudusoft.com\/es\/como-tener-exito-en-la-gobernanza-de-datos\/","title":{"rendered":"\u00bfC\u00f3mo tener \u00e9xito en la gobernanza de datos? | Gudu SQLFlow"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#e8eaf0;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1310.4px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\" style=\"line-height:26px;\"><h2><strong>\u00bfC\u00f3mo tener \u00e9xito en la gobernanza de datos?<\/strong><\/h2>\n<p>En este art\u00edculo, exploraremos<strong> C\u00f3mo tener \u00e9xito en la gobernanza de datos<\/strong>Si ha trabajado con grandes cantidades de datos, probablemente haya escuchado el t\u00e9rmino &quot;<a href=\"https:\/\/www.gudusoft.com\/es\/el-mejor-software-de-herramientas-de-gobernanza-de-datos\/\"><strong>gobernanza de datos<\/strong><\/a>Probablemente te hayas preguntado: \u00bfqu\u00e9 es? \u00bfEs adecuado para ti? \u00bfC\u00f3mo implementarlo? En pocas palabras, la gobernanza de datos es la estrategia para gestionar los datos: c\u00f3mo se almacenan, se accede a ellos, se verifican, se protegen y se utilizan. La gobernanza de datos incluye el desarrollo de esquemas de acceso: qui\u00e9n puede acceder, usar y compartir tus datos.<\/p>\n<p>Estos problemas cobran cada vez mayor importancia a medida que las empresas dependen de la recopilaci\u00f3n, el almacenamiento y el an\u00e1lisis de grandes cantidades de datos para alcanzar sus objetivos comerciales. Los datos se han convertido en una herramienta de lucro, un medio comercial y un secreto comercial para las empresas. Las filtraciones de datos pueden dar lugar a litigios y hacer que los consumidores pierdan la confianza en la actividad principal de una empresa.<\/p>\n<div id=\"attachment_5250\" style=\"width: 829px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-5250\" decoding=\"async\" class=\"size-full wp-image-5250\" src=\"https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Succeed_in_Data_Governance.png\" alt=\"\u00bfC\u00f3mo tener \u00e9xito en la gobernanza de datos?\" width=\"819\" height=\"517\" srcset=\"https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Succeed_in_Data_Governance-200x126.png 200w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Succeed_in_Data_Governance-300x189.png 300w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Succeed_in_Data_Governance-320x202.png 320w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Succeed_in_Data_Governance-400x253.png 400w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Succeed_in_Data_Governance-600x379.png 600w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Succeed_in_Data_Governance-700x441.png 700w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Succeed_in_Data_Governance-768x485.png 768w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Succeed_in_Data_Governance-800x505.png 800w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Succeed_in_Data_Governance.png 819w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><p id=\"caption-attachment-5250\" class=\"wp-caption-text\">\u00bfC\u00f3mo tener \u00e9xito en la gobernanza de datos?<\/p><\/div>\n<p>Si se deja que cada departamento procese los datos, se carecer\u00e1 de una estrategia unificada para su gesti\u00f3n y, en algunos casos, se dejar\u00e1 que cada departamento desarrolle sus propias estrategias. Esto es impensable, al igual que la falta de una estrategia para la gesti\u00f3n de inventarios f\u00edsicos, lo que permite a cada entidad producir, almacenar y vender productos a voluntad. El uso indebido de datos, como el uso indebido del inventario, puede costar millones de d\u00f3lares a las empresas, por lo que es necesario implementar estrategias para garantizar la coherencia, la seguridad y la disponibilidad de los datos. Estas pol\u00edticas aplicadas al dominio de los datos constituyen la gobernanza de datos.<\/p>\n<h3>Caracter\u00edsticas de la gobernanza de datos<\/h3>\n<p>A <strong><a href=\"https:\/\/www.gudusoft.com\/es\/estrategia-de-gobernanza-de-datos\/\">estrategia de gobernanza de datos<\/a><\/strong> Debe abarcar todo el ciclo de vida de los datos, desde su recopilaci\u00f3n hasta su gesti\u00f3n. Durante este ciclo, la gobernanza de datos debe abordar los siguientes aspectos:<\/p>\n<p>1. D\u00f3nde obtener los datos y c\u00f3mo obtenerlos: este es el punto de partida del ciclo de vida de los datos. La procedencia de los datos determina la base de una estrategia de gobernanza de datos. Por ejemplo, un factor importante para determinar la fuente de los datos es el tama\u00f1o del conjunto de datos. \u00bfSe recopilan los datos de los mercados objetivo, los clientes existentes y las redes sociales? \u00bfO se recurre a un proveedor externo para recopilar o analizar los datos que se recopilan? \u00bfCu\u00e1l es el flujo de datos de entrada? La gobernanza de datos debe abordar estas cuestiones, desarrollar estrategias para gestionar la recopilaci\u00f3n de datos, guiar a los proveedores externos para que procesen o analicen los datos que se recopilan, y controlar la ruta y el ciclo de vida de los datos.<\/p>\n<p>2. Validar datos, especialmente datos de m\u00faltiples fuentes, es un dolor de cabeza para <strong><a href=\"https:\/\/www.gudusoft.com\/es\/administradores-de-datos\/\">administradores de datos<\/a><\/strong>Distinguir los datos importantes de los que no lo son es solo el principio del problema. Si recopila datos de una empresa afiliada, debe asegurarse de que sean fiables. Si recopila datos de redes sociales, su estrategia debe incluir una forma de verificar los datos importantes. En cualquier caso, debe asegurarse de que los datos recopilados sean leg\u00edtimos y no hayan sido manipulados. Este problema es especialmente preocupante en entornos de computaci\u00f3n paralela, donde esta suele utilizarse para recopilar grandes cantidades de datos, a menudo mediante servicios en la nube, lo que aumenta el riesgo de seguridad.<\/p>\n<p>3. Las pol\u00edticas de gobernanza de datos deben abordar los problemas de almacenamiento, y las soluciones de almacenamiento dependen en gran medida del tama\u00f1o de los conjuntos de datos. Petabytes de big data deben almacenarse en sistemas seguros y redundantes, a menudo utilizando jerarqu\u00edas que proporcionan datos seg\u00fan la frecuencia de uso. De esta manera, los costosos sistemas en l\u00ednea proporcionan datos que se solicitan con frecuencia, mientras que los datos menos solicitados se almacenan en sistemas m\u00e1s econ\u00f3micos y con menor disponibilidad. Desafortunadamente, estos sistemas de menor prioridad tambi\u00e9n pueden ser menos seguros, lo que permite el acceso a datos sensibles pero poco solicitados. Por lo tanto, al dise\u00f1ar una soluci\u00f3n de almacenamiento de datos, una buena pol\u00edtica de gobernanza de datos debe considerar todos los aspectos.<\/p>\n<p>4. La gobernanza de datos debe desarrollar una estrategia de control de acceso que logre un equilibrio entre las necesidades y la seguridad. Permita el acceso a los datos cuando sea necesario para quienes los necesitan para realizar su trabajo. Por razones de seguridad, no deben poder acceder a los datos fuera de su autoridad. Solo se debe acceder a los datos bajo la premisa de solicitudes leg\u00edtimas, pero por razones de seguridad, el acceso a datos sensibles debe ser m\u00e1s dif\u00edcil y estar disponible solo para usuarios con un nivel de seguridad espec\u00edfico.<\/p>\n<p>Se deben establecer niveles de acceso para los usuarios y los propios datos, y es fundamental una estrecha interacci\u00f3n con RR. HH. y Compras durante la gesti\u00f3n de cuentas, ya que esto permite que los empleados que se marchan y los proveedores que dejan de trabajar ya no tengan acceso de forma oportuna. Gestionar estos detalles y garantizar la propiedad y la rendici\u00f3n de cuentas de los datos forman parte de una estrategia integral de gobernanza de datos.<\/p>\n<p>5. Usar\/Compartir\/Analizar. El uso de los datos es fundamental en una estrategia de gobernanza de datos. Entre sus posibles usos se incluyen la gesti\u00f3n de cuentas, la mejora de la experiencia del cliente, la publicidad dirigida, el an\u00e1lisis de mercado y el intercambio de datos con empresas afiliadas. Es necesario definir cuidadosamente qu\u00e9 datos se pueden compartir o utilizar con fines de marketing y protegerlos de ataques y filtraciones, ya que su uso est\u00e1 destinado exclusivamente a fines internos. Informe a los clientes que todas las empresas que recopilan datos deben cumplir con las normativas de uso e intercambio de datos. Garantizar el cumplimiento normativo en el uso de los datos es otra importante ventaja de contar con una pol\u00edtica de gobernanza de datos.<\/p>\n<p>6. La recopilaci\u00f3n, la verificaci\u00f3n, el almacenamiento, el acceso y el uso son componentes necesarios de un plan de seguridad, y debe existir una estrategia integral para abordar estas y otras preocupaciones de seguridad. Un programa de seguridad debe funcionar sin prohibir usuarios, pero las etapas del ciclo de vida de los datos pueden ser atacadas y comprometidas por inadvertencia. La b\u00fasqueda de la seguridad debe apoyar, en lugar de obstaculizar, el uso necesario. Una estrategia de gobernanza de datos debe desarrollar soluciones de seguridad de datos, incluyendo protocolos de acceso, cifrado de datos en reposo y en tr\u00e1nsito, y m\u00e1s.<\/p>\n<p>7. Administraci\u00f3n\/Metadatos. El ciclo de vida de los datos est\u00e1 incompleto sin administraci\u00f3n. Un ejemplo de administraci\u00f3n es la aplicaci\u00f3n de metadatos a un dato para identificar su recuperaci\u00f3n. Los metadatos incluyen la fuente de los datos, la fecha de generaci\u00f3n o recopilaci\u00f3n, la informaci\u00f3n sobre el nivel de acceso, la clasificaci\u00f3n sem\u00e1ntica y otros atributos requeridos por la empresa. La gobernanza de datos establece un vocabulario de metadatos que define su periodo de validez. Tenga en cuenta que los datos tambi\u00e9n expiran y, en alg\u00fan momento, solo pueden utilizarse para el an\u00e1lisis de datos hist\u00f3ricos.<\/p>\n<h3>Cuestiones organizativas de la gobernanza de datos<\/h3>\n<p>La creaci\u00f3n de una gobernanza de datos suele toparse con la resistencia de quienes temen no poder acceder a los datos que necesitan y de quienes hist\u00f3ricamente se han mostrado reacios a compartirlos por motivos de competencia. Una estrategia de gobernanza de datos debe abordar estas preocupaciones y ser aceptable para todas las partes. Las empresas acostumbradas a un entorno de silos de datos pueden tener dificultades para adaptarse a las nuevas estrategias de gobernanza de datos, pero la dependencia actual de grandes conjuntos de datos y los numerosos problemas de seguridad que conllevan hacen que la creaci\u00f3n e implementaci\u00f3n de pol\u00edticas de datos a nivel de toda la empresa sea una necesidad.<\/p>\n<p>Los datos forman parte cada vez m\u00e1s de la infraestructura empresarial, y las decisiones se toman a medida que la empresa procesa situaciones espec\u00edficas paso a paso. Esto se hace de forma puntual, a menudo en respuesta a un problema espec\u00edfico. Como resultado, la forma en que una empresa gestiona los datos puede variar de un departamento a otro, o incluso de un departamento a otro.<\/p>\n<p>Incluso si cada departamento ya cuenta con un plan razonable para el procesamiento de datos, estos planes pueden entrar en conflicto y la empresa deber\u00e1 buscar una soluci\u00f3n. Determinar los requisitos y las necesidades de almacenamiento de datos puede ser dif\u00edcil, y si no se hace correctamente, no se podr\u00e1 aprovechar el potencial de los datos para el marketing y la fidelizaci\u00f3n de clientes, adem\u00e1s de asumir responsabilidad legal en caso de una filtraci\u00f3n de datos.<\/p>\n<p>Another problem is that in a large company, departments compete for resources and compete to have their needs heard. Departments only need to ensure their own viability, whether it is a profitable business or a support centre, so they have a narrow vision and focus on their own needs, making it difficult to reach a compromise without mediation.<\/p>\n<p>El Consejo de Gobernanza de Datos crea pol\u00edticas de gobernanza de datos basadas en las pol\u00edticas de datos existentes, las necesidades no satisfechas y los posibles problemas de seguridad, estandarizando las pol\u00edticas de recopilaci\u00f3n, gesti\u00f3n, almacenamiento, acceso y uso de datos, y considerando las diferentes necesidades de los distintos departamentos y puestos. El Consejo de Gobernanza de Datos tambi\u00e9n act\u00faa como mediador, equilibrando necesidades contradictorias, conciliando las preocupaciones de seguridad con las necesidades de acceso y garantizando las pol\u00edticas de gesti\u00f3n de datos m\u00e1s eficientes y seguras.<\/p>\n<h3>\u00bfC\u00f3mo tener \u00e9xito en la gobernanza de datos?<\/h3>\n<p><strong>C\u00f3mo tener \u00e9xito en la gobernanza de datos: 1. Establecer una organizaci\u00f3n de gobernanza de datos. <\/strong><\/p>\n<p>El Data Governance Institute recomienda la creaci\u00f3n de un consejo de gobernanza de datos que eval\u00fae las aportaciones de los usuarios individuales y establezca una estrategia de gesti\u00f3n de datos para toda la empresa que aborde las necesidades de los usuarios internos, externos e incluso del departamento legal. El consejo debe incluir a las partes interesadas de todas las \u00e1reas de la empresa para garantizar que se satisfagan todas las necesidades y que todos los tipos de propietarios de datos est\u00e9n representados. Expertos en seguridad tambi\u00e9n deben formar parte del comit\u00e9. Es importante conocer los objetivos del consejo de gobernanza de datos, as\u00ed que piense por qu\u00e9 su organizaci\u00f3n necesita una estrategia de gobernanza de datos y expl\u00edquela con claridad.<\/p>\n<p><strong>C\u00f3mo tener \u00e9xito en la gobernanza de datos: 2. Desarrollar un marco que se adapte a una amplia gama de requisitos de datos. <\/strong><\/p>\n<p>El marco debe garantizar que las piezas se integren en un todo que cumpla con los requisitos de recopilaci\u00f3n, almacenamiento, recuperaci\u00f3n y seguridad. Para ello, una empresa debe definir claramente su estrategia integral de datos para dise\u00f1ar un marco que cubra todos los requisitos y operaciones necesarias. Las piezas deben planificarse conjuntamente para que se complementen entre s\u00ed, lo que ofrece numerosas ventajas, como la posibilidad de realizar la recuperaci\u00f3n en un entorno de alta seguridad.<\/p>\n<p>El cumplimiento normativo tambi\u00e9n debe dise\u00f1arse espec\u00edficamente como parte del marco para que se puedan rastrear e informar los asuntos regulatorios. El marco tambi\u00e9n incluye registros diarios y otras medidas de seguridad que alertan con anticipaci\u00f3n sobre ataques. La validaci\u00f3n de los datos antes de su uso tambi\u00e9n forma parte del marco. El Consejo de Gobernanza de Datos debe comprender cada parte del marco, aclarar su prop\u00f3sito y c\u00f3mo funciona a lo largo del ciclo de vida de los datos.<\/p>\n<p><strong>C\u00f3mo tener \u00e9xito en la gobernanza de datos: 3. Implementar una estrategia de datos. <\/strong><\/p>\n<p>Normalmente, una estrategia debe implementarse a peque\u00f1a escala para descubrir fallas en la planificaci\u00f3n, el marco y la infraestructura antes de implementarse en toda la empresa.<\/p>\n<p><strong>C\u00f3mo tener \u00e9xito en la gobernanza de datos \u2013 4. Contar con una organizaci\u00f3n de gobernanza de datos actualizada. <\/strong><\/p>\n<p>El Consejo de Gobernanza de Datos debe adaptarse a los nuevos tiempos, ya que las pol\u00edticas de gobernanza de datos sin duda deber\u00e1n ajustarse a medida que se expandan a nuevas \u00e1reas de negocio. Adem\u00e1s, a medida que la tecnolog\u00eda evoluciona, tambi\u00e9n deben hacerlo las pol\u00edticas de datos, adapt\u00e1ndose a las situaciones de seguridad, los m\u00e9todos de an\u00e1lisis de datos y las herramientas de gesti\u00f3n de datos.<\/p>\n<p><strong>C\u00f3mo tener \u00e9xito en la gobernanza de datos: 5. Conozca qu\u00e9 es una estrategia de datos exitosa. <\/strong><\/p>\n<p>Establezca m\u00e9tricas de \u00e9xito para medir el progreso. Establecer objetivos de gesti\u00f3n de datos le ayudar\u00e1 a identificar indicadores importantes de \u00e9xito y, a su vez, a garantizar que su estrategia de gobernanza de datos avance en la direcci\u00f3n deseada y necesaria.<\/p>\n<h3>Conclusi\u00f3n<\/h3>\n<p>Gracias por leer nuestro art\u00edculo. Esperamos que le ayude a comprender mejor c\u00f3mo lograr el \u00e9xito en la gobernanza de datos. Si desea obtener m\u00e1s informaci\u00f3n sobre la gobernanza de datos, le recomendamos visitar <strong><a href=\"https:\/\/sqlflow.gudusoft.com\/#\/\">Flujo de SQL de Gudu<\/a><\/strong> Para m\u00e1s informaci\u00f3n.<\/p>\n<p>Como uno de los\u00a0<strong><a href=\"https:\/\/www.dpriver.com\/blog\/2022\/05\/11\/best-data-lineage-tools\/\" target=\"_blank\" rel=\"noopener noreferrer\">Las mejores herramientas de linaje de datos<\/a><\/strong>\u00a0Disponible en el mercado hoy en d\u00eda, Gudu SQLFlow no solo puede analizar archivos de script SQL, obtener <strong><a href=\"https:\/\/www.gudusoft.com\/es\/que-son-los-datos-de-linaje-y-por-que-son-importantes\/\">linaje de datos<\/a><\/strong>, y realizar presentaciones visuales, pero tambi\u00e9n permitir que los usuarios proporcionen\u00a0<strong>linaje de datos<\/strong>\u00a0en formato CSV y realizar visualizaci\u00f3n.\u00a0<strong>(Publicado por Ryan el 24 de julio de 2022)<\/strong><\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":27,"featured_media":5262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[178],"tags":[137,183,59,323,75,324],"_links":{"self":[{"href":"https:\/\/www.gudusoft.com\/es\/wp-json\/wp\/v2\/posts\/5245"}],"collection":[{"href":"https:\/\/www.gudusoft.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gudusoft.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gudusoft.com\/es\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gudusoft.com\/es\/wp-json\/wp\/v2\/comments?post=5245"}],"version-history":[{"count":18,"href":"https:\/\/www.gudusoft.com\/es\/wp-json\/wp\/v2\/posts\/5245\/revisions"}],"predecessor-version":[{"id":5265,"href":"https:\/\/www.gudusoft.com\/es\/wp-json\/wp\/v2\/posts\/5245\/revisions\/5265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gudusoft.com\/es\/wp-json\/wp\/v2\/media\/5262"}],"wp:attachment":[{"href":"https:\/\/www.gudusoft.com\/es\/wp-json\/wp\/v2\/media?parent=5245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gudusoft.com\/es\/wp-json\/wp\/v2\/categories?post=5245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gudusoft.com\/es\/wp-json\/wp\/v2\/tags?post=5245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}