{"id":5222,"date":"2022-07-22T23:24:40","date_gmt":"2022-07-23T07:24:40","guid":{"rendered":"https:\/\/www.gudusoft.com\/?p=5222"},"modified":"2022-09-17T14:18:48","modified_gmt":"2022-09-17T22:18:48","slug":"how-to-select-the-best-data-governance-tools","status":"publish","type":"post","link":"https:\/\/www.gudusoft.com\/de\/so-wahlen-sie-die-besten-data-governance-tools-aus\/","title":{"rendered":"Wie w\u00e4hlt man die besten Data-Governance-Tools aus?"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#e8eaf0;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1310.4px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\" style=\"line-height:26px;\"><h2>Wie w\u00e4hlt man die besten Data-Governance-Tools aus?<\/h2>\n<p>Es gibt immer mehr Tools auf dem Markt, die die Effektivit\u00e4t von <strong><a href=\"https:\/\/www.gudusoft.com\/de\/was-ist-daten-governance\/\">Datenverwaltung<\/a><\/strong>, und neben bestehenden Softwareanbietern dr\u00e4ngen oft neue Wettbewerber in den Markt f\u00fcr Governance-Software. Daher wird es zunehmend schwieriger, zwischen den vielen Anbietern und Governance-Software zu w\u00e4hlen. Wenn Sie die <strong><a href=\"https:\/\/www.gudusoft.com\/de\/best-data-governance-tools-software\/\">die besten Data-Governance-Tools<\/a><\/strong>, dann sind Sie hier genau richtig. Wir haben diesen Artikel geschrieben \u2014 <em><strong>So w\u00e4hlen Sie die besten Data Governance-Tools aus<\/strong><\/em> \u2013 um Sie bei der Auswahl und Verwaltung von Lieferanten zu unterst\u00fctzen.<\/p>\n<div id=\"attachment_5225\" style=\"width: 877px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-5225\" decoding=\"async\" class=\"size-full wp-image-5225\" src=\"https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Select_the_Best_Data_Governance_Tools.png\" alt=\"Wie w\u00e4hlt man die besten Data-Governance-Tools aus?\" width=\"867\" height=\"472\" srcset=\"https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Select_the_Best_Data_Governance_Tools-200x109.png 200w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Select_the_Best_Data_Governance_Tools-300x163.png 300w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Select_the_Best_Data_Governance_Tools-400x218.png 400w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Select_the_Best_Data_Governance_Tools-600x327.png 600w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Select_the_Best_Data_Governance_Tools-768x418.png 768w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Select_the_Best_Data_Governance_Tools-800x436.png 800w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/07\/How_to_Select_the_Best_Data_Governance_Tools.png 867w\" sizes=\"(max-width: 867px) 100vw, 867px\" \/><p id=\"caption-attachment-5225\" class=\"wp-caption-text\">Wie w\u00e4hlt man die besten Data-Governance-Tools aus?<\/p><\/div>\n<h3>Bevor Sie ein Data-Governance-Tool kaufen, m\u00fcssen Sie vorbereitet sein.<\/h3>\n<p>Bevor Sie eine Kaufentscheidung treffen, m\u00fcssen Sie kl\u00e4ren, warum Sie die Governance-Software nutzen und welchen gesch\u00e4ftlichen Nutzen Sie daraus ziehen. Sobald Sie diese Informationen vorliegen haben, k\u00f6nnen Sie Governance-Produkte anhand dieser Informationen bewerten. Doch wie finden Sie heraus, welche Tools Ihren spezifischen Governance-Anforderungen am besten gerecht werden?<\/p>\n<p>Um die Auswahl an Data-Governance-Tools einzugrenzen, k\u00f6nnen wir die wichtigsten Governance-Tools auf dem Markt vergleichen. Diese Tools stammen haupts\u00e4chlich von 10 Anbietern und wir werden diese Produkte nach Nutzungsszenarien und Produktkategorien analysieren.<\/p>\n<h3>Bewerten Sie Data-Governance-Tools nach Anwendungsfall.<\/h3>\n<p>Die Diskussion \u00fcber den Nutzen von Data-Governance-Tools muss im Kontext spezifischer Gesch\u00e4ftsszenarien erfolgen. Sehen wir uns an, wie Anbieter die folgenden drei grundlegenden Anwendungsf\u00e4lle unterst\u00fctzen:<\/p>\n<p>Stark regulierte Branchen. Finanzdienstleister und Gesundheitsorganisationen, insbesondere in den USA, sind Beispiele f\u00fcr diese Art von Data-Governance-Anwendungsf\u00e4llen. Dieser Anwendungsfall erfordert, dass die Software umfassende Datenmanagementfunktionen bietet, einschlie\u00dflich der Unterst\u00fctzung der Konsistenz der Datenbedeutung, der Nachverfolgung von <strong><a href=\"https:\/\/www.gudusoft.com\/de\/whats-data-lineage-why-important\/\">Datenherkunft<\/a><\/strong>, Workflow und gut sichtbare t\u00e4gliche Datenverwaltungsprozesse.<\/p>\n<p>Werkzeuge, die <strong><a href=\"https:\/\/www.gudusoft.com\/de\/what-is-a-data-glossary\/\">Wirtschaftsglossar<\/a><\/strong> Zu den Funktionen zur Pflege generischer Datendefinitionen geh\u00f6ren: Alation <strong><a href=\"https:\/\/www.gudusoft.com\/de\/was-ist-der-datenkatalog-warum-sind-die-daten-datenprotokoll\/\">Datenkatalog<\/a><\/strong>, Adaptiver Metadata Manager, Collibra Data Governance Center, Data3Sixty Data Collaboration Suite, Diaku Axon, IBM InfoSphere Information Governance Catalog und SAS Data Governance.<\/p>\n<p>In manchen F\u00e4llen eignen sich bestimmte Produkte nur f\u00fcr bestimmte Branchen. Beispielsweise konzentriert sich die Governance-Software von IBM, Collibra und Diaku auf den Finanzsektor, w\u00e4hrend die Software von Information Builders Omni-Gen auf Gesundheitsdienstleister und Versicherungsunternehmen ausgerichtet ist.<\/p>\n<p>Dar\u00fcber hinaus variiert die Funktionalit\u00e4t des Glossars von Anbieter zu Anbieter. Bei einigen Anbietern stehen beispielsweise die Datenermittlung und Begriffssammlung im Mittelpunkt der Software. Andere Anbieter konzentrieren sich eher auf die Verwaltung von Synonymen und anderer komplexer Semantik. Die Tools unterscheiden sich auch in ihren M\u00f6glichkeiten zum Durchsuchen und Importieren von Metadaten. Beispielsweise bietet der Adaptive Metadata Manager die Metadatenerfassung, w\u00e4hrend andere Produkte wie Alation, Collibra und Data3Sixty einen interaktiveren Ansatz zur Datenermittlung unterst\u00fctzen.<\/p>\n<p>F\u00fcr den Anwendungsfall der Datenherkunftserfassung bieten verschiedene Tools unterschiedliche Funktionen. Manche Tools unterst\u00fctzen lediglich die Datenherkunft, andere helfen beim Extrahieren von Datenherkunftsinformationen aus einem Datensatz, und wieder andere erm\u00f6glichen die einfache Erfassung der Datenherkunft. Die Art und Weise, wie Sie die Datenherkunft unterst\u00fctzen, h\u00e4ngt stark von der Architektur der Anwendung ab (z. B. ob Sie ein Produkt eines Anbieters oder eine selbst entwickelte Anwendung verwenden usw.), der Infrastruktur und <strong><a href=\"https:\/\/www.gudusoft.com\/de\/was-ist-metadatenverwaltung\/\">Datenbankverwaltung<\/a><\/strong> Systemtechnik. Daher m\u00fcssen Sie bei Bedarf sicherstellen, dass Sie \u00fcber gute Kenntnisse in den oben genannten Bereichen verf\u00fcgen.<\/p>\n<p>Workflow- und Projektmanagementfunktionen sind in dieser g\u00e4ngigen Datenmanagementsoftware unterschiedlich implementiert. Jeder Anbieter hat seine eigene, einzigartige Methode zur Prozesssteuerung. Collibra hat mit Workflows begonnen und ist daher bereits mit Workflow-Management vertraut. Die Governance-Tools von SAP sind weitgehend, aber nicht vollst\u00e4ndig in die ERP-Suite integriert. Auch adaptive Workflow-Funktionen erfreuen sich in letzter Zeit zunehmender Beliebtheit. Workflow ist branchenspezifisch. Pr\u00fcfen Sie daher bei der Auswahl einer Managementsoftware Ihre Anforderungen an diese Funktion sorgf\u00e4ltig, um sicherzustellen, dass das gew\u00e4hlte Endprodukt Ihren Anforderungen wirklich entspricht.<\/p>\n<p>Es besteht dringender Bedarf, wichtige Datendom\u00e4nen zu konsolidieren. Moderatorgesteuerte Data-Governance-Projekte basieren in erster Linie auf den Anforderungen des Master Data Management (MDM) und der Golden-Copy-Bem\u00fchungen. Anbieterprodukte erweitern diese Funktionalit\u00e4t durch die Kombination eingebetteter MDM-Repositories und <a href=\"https:\/\/www.gudusoft.com\/de\/so-verbessern-sie-die-datenqualitat\/\"><strong>Datenqualit\u00e4t<\/strong><\/a> Wartungstools mit Data-Governance-Funktionen. Anbieter wie SAP integrieren Datenqualit\u00e4t, Gesch\u00e4ftsausrichtung, Wertbewertung und Strategiemanagement. SAS integriert ebenfalls Data Governance, Datenqualit\u00e4t und Richtlinienmanagement mit MDM-Funktionen. Information Builders integriert Datenqualit\u00e4t und Datenreparatur mit MDM-Managementfunktionen.<\/p>\n<p>Es ist wichtig zu beachten, dass viele Data-Governance-Tools nur f\u00fcr bestimmte Anwendungsf\u00e4lle des Informationsmanagements wie Big Data oder MDM geeignet sind, w\u00e4hrend andere universell einsetzbar sind. Ihr spezifischer Anwendungsfall bestimmt Ihre Entscheidung.<\/p>\n<p>Verf\u00fcgbarkeit und Zug\u00e4nglichkeit von Daten. Data Governance wird derzeit in der Big Data-Analyse und Business Intelligence eingesetzt, um eine hohe Effizienz der Datenmigration sowie die Zuverl\u00e4ssigkeit, Sicherheit und Relevanz der Datendimensionen zu gew\u00e4hrleisten. Data-Governance-Tools in diesem Bereich \u00e4hneln den anderen oben genannten Anwendungsf\u00e4llen, werden jedoch anders eingesetzt.<\/p>\n<p>Informatica Master Data Management ist auf Big Data-Unterst\u00fctzung spezialisiert. Die Datenvalidit\u00e4t wird durch den Einsatz von Datenmanagement, das von den meisten Data-Governance-Tools, einschlie\u00dflich Collibra, abgedeckt wird, erh\u00f6ht.<\/p>\n<p>Viele Tools sind mit grundlegenden Funktionen zur Datenqualit\u00e4tssicherung verkn\u00fcpft oder bieten diese direkt an. Beispielsweise bietet SAPs Master Data Governance umfassende Funktionen zum Datenqualit\u00e4tsmanagement. Wie bereits erw\u00e4hnt, bietet Omni-Gen von Information Builder Datenreparatur und Datenspezifikation. Informatica bietet zudem Optionen zur Anbindung an Datenqualit\u00e4tsmanagement-Funktionen.<\/p>\n<h3>Weitere \u00dcberlegungen zur Bewertung von Data Governance Tools<\/h3>\n<p>Tats\u00e4chlich spiegeln Data-Governance-Tools wider, wie Daten erhoben und verarbeitet werden. Das wiederum bedeutet, dass Data-Governance-Tools gut zu Ihrem Gesch\u00e4ftsmodell und Ihrer Technologie passen m\u00fcssen.<\/p>\n<p>Anbieter bieten eine breite Palette an Lizenzierungs- und Bereitstellungsoptionen an, von der lokalen Bereitstellung \u00fcber Remote-Dienste und Webdienste bis hin zu traditionellen Client-Server-Modellen. Sie k\u00f6nnen das Produkt nun mit einem Abonnement testen und anschlie\u00dfend entscheiden, ob Sie es lokal bereitstellen m\u00f6chten. Dasselbe gilt f\u00fcr die Infrastruktur. Obwohl viele Anbieter beispielsweise Webdienste anbieten, funktionieren einige m\u00f6glicherweise nicht so gut wie andere. Viele Anbieter bieten verschiedene Verbindungsoptionen an, die Art und Weise der Anbindung an andere Dateistrukturen variiert jedoch stark. Alle Optionen k\u00f6nnen vom Benutzer selektiv hinzugef\u00fcgt werden, allerdings erh\u00f6ht sich dadurch der Preis. Es ist wichtig, die richtigen Tools f\u00fcr Ihre spezifische Infrastruktur auszuw\u00e4hlen.<\/p>\n<p>Wie bei vielen anderen Softwaretools m\u00fcssen Sie das Data-Governance-Tool vor dem Kauf testen und sicherstellen, dass es zu Ihrem Data-Governance-Anwendungsfall passt. Oftmals funktionieren diese Produkte unter bestimmten Umst\u00e4nden und Anforderungen gut. In einem anderen Szenario war das gleiche Produkt jedoch nicht so effektiv.<\/p>\n<p>Dar\u00fcber hinaus funktionieren Data-Governance-Tools tendenziell besser mit Software desselben Anbieters als mit Software verschiedener Anbieter. Manchmal entspricht die Benutzeroberfl\u00e4che einiger Anbieter nicht Ihren Anforderungen, w\u00e4hrend die anderer Anbieter dies tut. Bedenken Sie, dass die meisten Nutzer dieser Tools Business-Datenmanager oder andere Nicht-IT-Mitarbeiter sind. Sie sind ihren Anbietern m\u00f6glicherweise nicht so treu wie in anderen Bereichen des Datenmanagements.<\/p>\n<p>Ein wichtiger Aspekt bei der Bereitstellung dieser Tools ist die Nutzung der Infrastruktur \u2013 ob als Webdienst, auf lokalen Servern oder in der Cloud? Einige Data-Governance-Produkte lassen sich flexibel einsetzen. Wenn Ihre Unternehmensleitung also fest auf eine serviceorientierte Architektur setzt, m\u00fcssen Sie sich \u00fcber die Unterschiede im Klaren sein. Viele Anbieter bieten Cloud-basierte Lizenzen an. So bleiben Data-Governance-Tools auch ohne gr\u00f6\u00dfere interne Technologie\u00e4nderungen funktionsf\u00e4hig.<\/p>\n<p>Mit der Zeit ben\u00f6tigen Sie m\u00f6glicherweise mehrere Anbieter, damit Ihre Data-Governance-Tools Ihren Anforderungen entsprechen. In diesem Fall m\u00fcssen Sie sicherstellen, dass die Produkte verschiedener Anbieter zusammenarbeiten. W\u00e4hrend fast alle Tools gemeinsame Zugriffsoptionen (wie SQL) bieten, bieten einige, wie Adaptive, Collibra, IBM InfoSphere Information Governance Catalog und SAS, viele komplexe Verbindungsm\u00f6glichkeiten. Bei Projekten, die Optimierungen oder Proof-of-Concept-Pr\u00fcfungen erfordern, muss dieser Aspekt gr\u00fcndlich validiert werden. Die Art Ihrer Infrastruktur und Ihres Technologie-Stacks hat erhebliche Auswirkungen auf die Interoperabilit\u00e4t von Produkten verschiedener Anbieter.<\/p>\n<p>Einige Tool-Suiten eignen sich besser f\u00fcr gro\u00dfe Unternehmen oder solche, die viel Geld in denselben Anbieter investieren. Kits von IBM, Informatica, Information Builders, SAP und SAS sind f\u00fcr diese gro\u00dfen Unternehmen zweifellos die erste Wahl. Der Markt f\u00fcr Data-Governance-Tools ist jedoch noch nicht ausgereift genug, um die Angebote anderer kleinerer Anbieter zu ignorieren. Adaptive, Alation, Collibra, Data3Sixty und Daiku bieten Funktionen, Preise und Bereitstellungsoptionen, die auch vielen Unternehmen zur Verf\u00fcgung stehen.<\/p>\n<p>Der Markt f\u00fcr Data-Governance-Software kann etwas chaotisch sein. Wir hoffen, dass Sie die Vorteile von Data-Governance-Tools f\u00fcr Ihr Unternehmen verstehen und die richtigen Data-Governance-Tools f\u00fcr Ihr Unternehmen ausw\u00e4hlen k\u00f6nnen.<\/p>\n<h3>Abschluss<\/h3>\n<p>Vielen Dank f\u00fcr das Lesen unseres Artikels. Wir hoffen, dass er Ihnen hilft, besser zu verstehen <strong>So w\u00e4hlen Sie die besten Data-Governance-Tools aus<\/strong>Wenn Sie mehr \u00fcber Data Governance Tools erfahren m\u00f6chten, empfehlen wir Ihnen einen Besuch auf <strong><a href=\"https:\/\/www.gudusoft.com\/de\/\">Gudu SQLFlow<\/a><\/strong> f\u00fcr weitere Informationen.<\/p>\n<p>Als einer der <strong><a href=\"https:\/\/www.dpriver.com\/blog\/2022\/05\/11\/best-data-lineage-tools\/\">die besten Datenherkunftstools<\/a><\/strong> Gudu SQLFlow ist ein heute auf dem Markt erh\u00e4ltliches Tool, das nicht nur SQL-Skriptdateien analysiert, Datenherkunft ermittelt und visuelle Darstellungen erm\u00f6glicht, sondern auch die Bereitstellung von Datenherkunft im CSV-Format und die visuelle Darstellung. (Ver\u00f6ffentlicht von Ryan am 23. Juli 2022)<\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":27,"featured_media":5243,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[178],"tags":[321,163,57,137,268,136,322,75],"_links":{"self":[{"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/posts\/5222"}],"collection":[{"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/comments?post=5222"}],"version-history":[{"count":20,"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/posts\/5222\/revisions"}],"predecessor-version":[{"id":5244,"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/posts\/5222\/revisions\/5244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/media\/5243"}],"wp:attachment":[{"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/media?parent=5222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/categories?post=5222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/tags?post=5222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}