{"id":3381,"date":"2022-04-20T03:32:06","date_gmt":"2022-04-20T11:32:06","guid":{"rendered":"https:\/\/www.gudusoft.com\/?p=3381"},"modified":"2022-06-09T20:46:39","modified_gmt":"2022-06-10T04:46:39","slug":"whats-data-catalog-why-data-datalog","status":"publish","type":"post","link":"https:\/\/www.gudusoft.com\/de\/was-ist-der-datenkatalog-warum-sind-die-daten-datenprotokoll\/","title":{"rendered":"Was ist ein Datenkatalog? | Warum brauchen Sie einen Datenkatalog?"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#e8eaf0;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1310.4px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\" style=\"line-height:26px;\"><h1>Was ist ein Datenkatalog? | Warum brauchen Sie einen Datenkatalog?<\/h1>\n<p><strong>Was ist <a href=\"https:\/\/wiki.gccollab.ca\/index.php?title=Data_Catalog&amp;mobileaction=toggle_view_desktop\">Datenkatalog<\/a><\/strong>? <strong>Warum brauche ich einen Datenkatalog?<\/strong> <strong>Was sind die Funktionen und Vorteile davon?<\/strong> Wenn Sie Antworten auf diese Fragen suchen, sind Sie hier genau richtig. In diesem Beitrag werfen wir einen genaueren Blick auf den Datenkatalog, um Ihnen ein besseres Verst\u00e4ndnis zu vermitteln.<\/p>\n<div id=\"attachment_3387\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-3387\" decoding=\"async\" class=\"size-full wp-image-3387\" src=\"https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/04\/data_catalog.png\" alt=\"Datenkatalog\" width=\"600\" height=\"440\" srcset=\"https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/04\/data_catalog-200x147.png 200w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/04\/data_catalog-300x220.png 300w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/04\/data_catalog-400x293.png 400w, https:\/\/www.gudusoft.com\/wp-content\/uploads\/2022\/04\/data_catalog.png 600w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-3387\" class=\"wp-caption-text\">Datenkatalog<\/p><\/div>\n<h2><strong>Was ist ein Datenkatalog?<\/strong>?<\/h2>\n<p>Kurz gesagt ist ein Datenkatalog eine geordnete Liste der Datenbest\u00e4nde einer Organisation. Er verwendet Metadaten, um Organisationen bei der Verwaltung ihrer Daten zu unterst\u00fctzen. <span class=\"Y2IQFc\" lang=\"en\">Dar\u00fcber hinaus unterst\u00fctzt es Datenexperten beim Sammeln, Organisieren, Zugreifen und Anreichern von Metadaten, um die Datenermittlung und -verwaltung zu unterst\u00fctzen.<\/span><\/p>\n<h2>Warum brauchen Sie einen Datenkatalog?<\/h2>\n<p><span class=\"Y2IQFc\" lang=\"en\">Da mehr Daten als je zuvor verf\u00fcgbar sind, ist es schwieriger denn je, die richtigen Daten zu finden. Gleichzeitig gibt es mehr Regeln und Vorschriften als je zuvor \u2013 die DSGVO ist nur eine davon. Daher ist nicht nur der Datenzugriff eine Herausforderung, sondern auch die Datenverwaltung. Es ist \u00e4u\u00dferst wichtig zu verstehen, welche Art von Daten Sie aktuell haben, wer sie \u00fcbertr\u00e4gt, wof\u00fcr sie verwendet werden und wie Sie sie sichern m\u00fcssen. Vermeiden Sie jedoch auch, zu viele Schichten und H\u00fcllen um die Daten zu legen, denn wenn die Daten zu schwer zu verwenden sind, sind sie nutzlos.<\/span><\/p>\n<h2>Was sind die Funktionen und Vorteile eines Datenkatalogs?<\/h2>\n<p>In den letzten Jahren hat das Konzept von Datenverzeichnissen aufgrund der zunehmenden Datenmenge, die verwaltet und abgerufen werden muss, an Popularit\u00e4t gewonnen. Cloud, Big Data Analytics, k\u00fcnstliche Intelligenz und maschinelles Lernen haben begonnen, die Art und Weise zu ver\u00e4ndern, wie wir Daten sehen, verwalten und nutzen \u2013 nicht nur verwalten, sondern auch optimal nutzen und darauf zugreifen.<\/p>\n<p>Die richtige Verwendung eines Datenkatalogs bietet folgende Vorteile:<\/p>\n<ol>\n<li><span class=\"Y2IQFc\" lang=\"en\"><span class=\"Y2IQFc\" lang=\"en\">Kosten sparen\u00a0<\/span><\/span><\/li>\n<li>Verbesserung der Betriebseffizienz<\/li>\n<li>mehr Wettbewerbsvorteile<\/li>\n<li>besseres Kundenerlebnis<\/li>\n<li>Betrug und Risikovorteil<\/li>\n<\/ol>\n<h2>Was ist erforderlich, um die Daten im Datenkatalog optimal zu nutzen?<\/h2>\n<p>Lassen Sie uns also einen Schritt zur\u00fcckgehen und Metadaten kurz denjenigen erkl\u00e4ren, die damit vielleicht nicht ganz vertraut sind. Was sind Metadaten? Es gibt drei Arten von Metadaten:<\/p>\n<ul>\n<li>Technische Metadaten: Beziehen sich auf Schemata, Tabellen, Spalten, Dateinamen, Berichtsnamen \u2013 alles, was im Quellsystem aufgezeichnet ist.<\/li>\n<li>Gesch\u00e4ftsmetadaten: Hierbei handelt es sich in der Regel um das Gesch\u00e4ftswissen des Benutzers \u00fcber die Verm\u00f6genswerte der Organisation. Dies kann Gesch\u00e4ftsbeschreibungen, Bewertungen, Anmerkungen, Klassifizierungen, Eignung, Bewertungen usw. umfassen.<\/li>\n<li>Operative Metadaten: Wann wird dieses Objekt aktualisiert? Welcher ETL-Job hat es erstellt? Wie oft greift der Benutzer auf eine Tabelle zu \u2013 welche?<\/li>\n<\/ul>\n<p>In den letzten Jahren hat sich die Nutzung dieser wertvollen Metadaten grundlegend ver\u00e4ndert. Fr\u00fcher wurden Metadaten haupts\u00e4chlich f\u00fcr Audits verwendet, <strong><a href=\"https:\/\/www.gudusoft.com\/de\/whats-data-lineage-why-important\/\">Abstammung<\/a><\/strong>und Berichterstattung. Doch heutzutage verschieben technologische Innovationen wie serverlose Verarbeitung, grafische Datenbanken und insbesondere neue oder leichter zug\u00e4ngliche Technologien f\u00fcr k\u00fcnstliche Intelligenz und maschinelles Lernen die Grenzen und erm\u00f6glichen durch Metadaten Dinge, die zuvor in diesem Umfang unm\u00f6glich waren.<\/p>\n<p>Today, metadata can be used to enhance data management. From self-service data preparation to access control based on roles and data content, automatic data entry, anomaly monitoring and alarm, automatic allocation and scaling of resources, etc. All of these can now be enhanced with the help of metadata. And the data catalog uses metadata to help you manage more data than ever before.<\/p>\n<h2 class=\"rw-ptitle\">Was sollte ein guter Datenkatalog bieten?<\/h2>\n<ul>\n<li><strong>Suche und Entdeckung<\/strong>Ein guter Datenkatalog sollte \u00fcber flexible Such- und Filteroptionen verf\u00fcgen, um schnell relevante Datens\u00e4tze f\u00fcr Data Science, Analyse oder Data Engineering zu finden und Metadaten basierend auf einer technischen Datenhierarchie zu durchsuchen. Dar\u00fcber hinaus sollte ein guter Datenkatalog die Eingabe technischer Informationen, benutzerdefinierter Tags oder Gesch\u00e4ftsbegriffe erm\u00f6glichen und die Suchfunktionen verbessern.<\/li>\n<li><strong>Erhalten Sie Metadaten aus einer Vielzahl von Quellen. <\/strong>Ein guter Datenkatalog kann technische Metadaten aus einer Vielzahl verbundener Datenbest\u00e4nde erfassen, darunter Objektspeicher, Datenbanken f\u00fcr autonomes Fahren, lokale Systeme usw.<\/li>\n<li><strong>Metadatenkuratierung.<\/strong> Ein guter Datenkatalog sollte Fachexperten die M\u00f6glichkeit bieten, Gesch\u00e4ftswissen in Form von unternehmensweiten Glossaren, Bezeichnungen, Verkn\u00fcpfungen, benutzerdefinierten Anmerkungen, Kategorien, Bewertungen usw. bereitzustellen.<\/li>\n<li><strong>Automatisierung und Datenintelligenz.<\/strong> K\u00fcnstliche Intelligenz und maschinelles Lernen sind im genannten Datenumfang h\u00e4ufig erforderlich. Alle menschlichen Aufgaben, die automatisiert werden k\u00f6nnen, sollten durch maschinelles Lernen und die Erfassung von Metadaten automatisiert werden. Dar\u00fcber hinaus k\u00f6nnen KI und maschinelles Lernen Daten wirklich bereichern, beispielsweise durch die Bereitstellung von Datenempfehlungen f\u00fcr Nutzer von Datenkatalogen und anderen Diensten auf modernen Datenplattformen.<\/li>\n<li><strong>Funktionen auf Unternehmensebene.<\/strong> Ihre Daten sind wichtig, und Sie ben\u00f6tigen f\u00fcr deren optimale Nutzung unternehmensweite Funktionen wie Identit\u00e4ts- und Zugriffsverwaltung sowie wichtige Funktionen \u00fcber REST-APIs. Dies bedeutet auch, dass Kunden und Partner Metadaten (z. B. benutzerdefinierte Harvester) bereitstellen und Datenkatalogfunktionen \u00fcber REST in ihren eigenen Anwendungen bereitstellen k\u00f6nnen.<\/li>\n<li>Dar\u00fcber hinaus sollte ein guter Datenkatalog zu einem De-facto-Systemkatalog werden, der Abstraktionen \u00fcber alle Persistenzebenen hinweg bietet, wie z. B. Objektspeicher, Hadoop, Datenbanken, Data Warehouses und Abfragedienste, die \u00fcber alle Datenspeicher hinweg funktionieren.<\/li>\n<\/ul>\n<h2>Abschluss<\/h2>\n<p>Vielen Dank f\u00fcr das Lesen unseres Artikels. Wir hoffen, dass er Ihnen dabei hilft, ein besseres Verst\u00e4ndnis zu erlangen von <strong>Was ist ein Datenkatalog?<\/strong>Wenn Sie mehr erfahren m\u00f6chten \u00fcber <strong>Datenkatalog und seine Funktionen und Vorteile<\/strong>, empfehlen wir Ihnen einen Besuch <strong><a href=\"https:\/\/www.gudusoft.com\/de\/\">Gudu SQLFlow<\/a><\/strong> f\u00fcr weitere Informationen. Nochmals vielen Dank! <strong>(Ver\u00f6ffentlicht von Ryan am<\/strong> <b>20. April 2022)<\/b><\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":27,"featured_media":3408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,178],"tags":[57,58,54],"_links":{"self":[{"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/posts\/3381"}],"collection":[{"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/comments?post=3381"}],"version-history":[{"count":22,"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/posts\/3381\/revisions"}],"predecessor-version":[{"id":3436,"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/posts\/3381\/revisions\/3436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/media\/3408"}],"wp:attachment":[{"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/media?parent=3381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/categories?post=3381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gudusoft.com\/de\/wp-json\/wp\/v2\/tags?post=3381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}